{"id":8076,"date":"2019-06-10T03:40:41","date_gmt":"2019-06-10T03:40:41","guid":{"rendered":"https:\/\/saloanoticias.com\/v1\/?p=8076"},"modified":"2019-06-10T03:42:52","modified_gmt":"2019-06-10T03:42:52","slug":"bomba-moro-teria-condenado-lula-sem-provas-para-se-auto-promover","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/bomba-moro-teria-condenado-lula-sem-provas-para-se-auto-promover\/","title":{"rendered":"BOMBA: MORO TERIA CONDENADO LULA SEM PROVAS PARA SE AUTOPROMOVER ?"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-8077\" src=\"https:\/\/saloanoticias.com\/v1\/wp-content\/uploads\/2019\/06\/portugal-e-um-estado-de-direito-doutor-moro-por-manuel-carvalho-moro-lula-marques7.jpg\" alt=\"\" \/>Mensagens atribu\u00eddas ao procurador\u00a0<strong>Deltan Dallagnol,<\/strong>\u00a0do Minist\u00e9rio P\u00fablico Federal\u00a0<strong>(MPF), <\/strong>e ao ministro da Justi\u00e7a\u00a0<strong>Sergio Moro,<\/strong>\u00a0divulgadas ontem pelo site The Intercept Brasil, mostram os dois combinando atua\u00e7\u00f5es enquanto trabalharam na opera\u00e7\u00e3o Lava-Jato. O site divulgou trocas de mensagens de Dallagnol e Moro que fazem refer\u00eancias ao processo em que o ex-presidente Luiz In\u00e1cio Lula da Silva (PT) foi condenado no caso do tr\u00edplex de Guaruj\u00e1.The Intercept Brasil informou que obteve o material de uma fonte an\u00f4nima, que pediu sigilo.<\/p>\n<p>O pacote inclui mensagens privadas e de grupos da for\u00e7a-tarefa no aplicativo Telegram de 2015 a 2018. Em uma das mensagens de texto, no dia 21 de fevereiro de 2016, Moro sugeriu altera\u00e7\u00f5es no calend\u00e1rio das opera\u00e7\u00f5es da for\u00e7a-tarefa da Lava Jato em Curitiba, em decorr\u00eancia de desdobramentos pol\u00edticos. Dallagnol, de acordo com o site, disse ao magistrado que haveria problemas log\u00edsticos para acatar a sugest\u00e3o.<\/p>\n<p>Em 31 de agosto de 2016, Moro teria questionado, de acordo com The Intercept, o ritmo das pris\u00f5es e apreens\u00f5es ao perguntar se a for\u00e7a-tarefa n\u00e3o estaria muito tempo sem promover opera\u00e7\u00f5es. &#8220;N\u00e3o \u00e9 muito tempo sem opera\u00e7\u00e3o?&#8221;, disse Moro segundo o site. A \u00faltima fase da Lava-Jato, de acordo com o site, havia sido feita 29 dias antes \u2014 a opera\u00e7\u00e3o Resta Um, com foco na empreiteira Queiroz Galv\u00e3o. Pelo conte\u00fado das mensagens divulgadas, Dallagnol concorda com a observa\u00e7\u00e3o sobre o tempo da demora. Com o vazamento das conversas, cai como que uma bomba sobre a Opera\u00e7\u00e3o Lava Jato, e, questionasse agora, a legalidade da pris\u00e3o e condena\u00e7\u00e3o do ex-presidente Lula no caso do apartamento tr\u00edplex no Guaruj\u00e1, sem falar no fato de que o atual Ministro S\u00e9rgio Moro tenha usado a sua fun\u00e7\u00e3o de juiz da Lava Jato para se auto promover.<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Mensagens atribu\u00eddas ao procurador\u00a0Deltan Dallagnol,\u00a0do Minist\u00e9rio P\u00fablico Federal\u00a0(MPF), e ao ministro da Justi\u00e7a\u00a0Sergio Moro,\u00a0divulgadas ontem pelo site The Intercept Brasil, mostram os dois combinando atua\u00e7\u00f5es enquanto trabalharam na opera\u00e7\u00e3o Lava-Jato. O site divulgou trocas de mensagens de Dallagnol e Moro que fazem refer\u00eancias ao processo em que o ex-presidente Luiz In\u00e1cio Lula da Silva (PT) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-8076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/8076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=8076"}],"version-history":[{"count":2,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/8076\/revisions"}],"predecessor-version":[{"id":8079,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/8076\/revisions\/8079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media\/8077"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=8076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=8076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=8076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}