{"id":3758,"date":"2017-12-08T11:52:00","date_gmt":"2017-12-08T11:52:00","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2017\/12\/08\/cumprimento-de-profecia-estados-unidos-reconhecem-jerusalem-como-capital-de-israel\/"},"modified":"2017-12-08T11:52:00","modified_gmt":"2017-12-08T11:52:00","slug":"cumprimento-de-profecia-estados-unidos-reconhecem-jerusalem-como-capital-de-israel","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/cumprimento-de-profecia-estados-unidos-reconhecem-jerusalem-como-capital-de-israel\/","title":{"rendered":"\u201cCUMPRIMENTO DAS PROFECIAS\u201d: ESTADOS UNIDOS RECONHECEM JERUSAL\u00c9M COMO A CAPITAL DE ISRAEL"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/trump-israelt-510x340.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"trump israelt-510x340\" style=\"border-top: 0px; border-right: 0px; background-image: none; border-bottom: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 0px auto 10px; border-left: 0px; display: block; padding-right: 0px\" border=\"0\" alt=\"trump israelt-510x340\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/trump-israelt-510x340_thumb.jpg\" width=\"1461\" height=\"973\"><\/a>O presidente dos Estados Unidos, <\/font><a href=\"http:\/\/g1.globo.com\/tudo-sobre\/donald-trump\"><font size=\"3\" face=\"Arial\">Donald Trump<\/font><\/a><font size=\"3\" face=\"Arial\">, anunciou nesta quarta-feira (6) que reconhece Jerusal\u00e9m como capital de <\/font><a href=\"http:\/\/g1.globo.com\/tudo-sobre\/israel\/\"><font size=\"3\" face=\"Arial\">Israel<\/font><\/a><font size=\"3\" face=\"Arial\"> e que pediu ao Departamento de Estado que inicie o processo de transferir para l\u00e1 a embaixada americana atualmente instalada em Tel Aviv. <\/font><font size=\"3\" face=\"Arial\">O an\u00fancio foi feito um dia ap\u00f3s diversos apelos da comunidade internacional para que a decis\u00e3o n\u00e3o fosse tomada. O reconhecimento da cidade como capital \u00e9 considerado pol\u00eamico, uma vez que os palestinos querem Jerusal\u00e9m Oriental como capital de seu futuro Estado, e a comunidade internacional n\u00e3o reconhece a reivindica\u00e7\u00e3o israelense sobre a cidade como um todo.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">&#8220;Meu an\u00fancio marca o come\u00e7o de uma nova abordagem no conflito entre Israel e palestinos&#8221;, anunciou Trump no in\u00edcio de seu discurso feito na Casa Branca. <\/font><font size=\"3\" face=\"Arial\">&#8220;Hoje finalmente reconhecemos o \u00f3bvio: que Jerusal\u00e9m \u00e9 a capital de Israel&#8221;, disse Trump. &#8220;Isso \u00e9 nada mais nada menos do que o reconhecimento da realidade. Tamb\u00e9m \u00e9 a coisa certa a fazer. \u00c9 algo que tem que ser feito&#8221;. <\/font><font size=\"3\" face=\"Arial\">&#8220;Com o an\u00fancio reafirmo o comprometimento da minha administra\u00e7\u00e3o com um futuro de paz&#8221;, disse o presidente.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Trump afirmou que os EUA est\u00e3o &#8220;profundamente comprometidos&#8221; em facilitar um &#8220;acordo de paz aceit\u00e1vel&#8221; tanto para israelenses como para palestinos e em apoiar uma solu\u00e7\u00e3o de dois Estados no Oriente M\u00e9dio, caso os dois lados queiram isso. <\/font><font size=\"3\" face=\"Arial\">Para o presidente americano, Jerusal\u00e9m deve continuar sendo o lugar sagrado e local de culto de judeus, mu\u00e7ulmanos e crist\u00e3os. Trump tamb\u00e9m disse que o dia pede &#8220;calma, vozes de modera\u00e7\u00e3o&#8221;, para que a ordem prevale\u00e7a sobre o \u00f3dio.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Ele disse que o vice-presidente Mike Pence ir\u00e1 ao Oriente M\u00e9dio nos pr\u00f3ximos dias. <\/font><font size=\"3\" face=\"Arial\">Com o an\u00fancio, Trump cumpre uma promessa feita ainda durante a campanha eleitoral de 2016, como uma forma de satisfazer a base pr\u00f3-Israel de direita que o ajudou a conquistar a presid\u00eancia. <\/font><font size=\"3\" face=\"Arial\">Sua decis\u00e3o faz com que seja cumprida a lei que prev\u00ea o reconhecimento de Jerusal\u00e9m como capital que foi adotada pelo Congresso americano em 1995. A aplica\u00e7\u00e3o da lei vinha sendo adiada nas \u00faltimas duas d\u00e9cadas, sob justificativa de &#8220;interesses de seguran\u00e7a nacional&#8221;. Em junho, o pr\u00f3prio Trump adiou a aplica\u00e7\u00e3o da lei por mais seis meses.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">&#8220;Depois de mais de duas d\u00e9cadas de adiamento, n\u00e3o estamos mais perto de um acordo de paz duradouro entre Israel e palestinos&#8221;, disse Trump. <\/font><font size=\"3\" face=\"Arial\">&#8220;Seria loucura assumir que repetir a mesma f\u00f3rmula produziria um resultado diferente ou melhor&#8221;. <strong><font size=\"2\">Fonte: g1.globo.com<\/font><\/strong><\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>O presidente dos Estados Unidos, Donald Trump, anunciou nesta quarta-feira (6) que reconhece Jerusal\u00e9m como capital de Israel e que pediu ao Departamento de Estado que inicie o processo de transferir para l\u00e1 a embaixada americana atualmente instalada em Tel Aviv. O an\u00fancio foi feito um dia ap\u00f3s diversos apelos da comunidade internacional para que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3758","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/3758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=3758"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/3758\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=3758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=3758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=3758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}