{"id":3756,"date":"2017-12-07T11:00:00","date_gmt":"2017-12-07T11:00:00","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2017\/12\/07\/pt-e-pmdb-estao-cada-vez-mais-proximos-em-5-estados\/"},"modified":"2017-12-07T11:00:00","modified_gmt":"2017-12-07T11:00:00","slug":"pt-e-pmdb-estao-cada-vez-mais-proximos-em-5-estados","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/pt-e-pmdb-estao-cada-vez-mais-proximos-em-5-estados\/","title":{"rendered":"PT E PMDB PODEM CAMINHAR JUNTOS EM 5 ESTADOS BRASILEIROS"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/img_3887.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"IMG_3887\" style=\"border-top: 0px; border-right: 0px; background-image: none; border-bottom: 0px; float: left; padding-top: 0px; padding-left: 0px; margin: 5px 5px 0px 0px; border-left: 0px; display: inline; padding-right: 0px\" border=\"0\" alt=\"IMG_3887\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/img_3887_thumb.jpg\" width=\"324\" align=\"left\" height=\"176\"><\/a>O PT far\u00e1 uma reuni\u00e3o da Executiva e do Diret\u00f3rio nacionais na semana que vem, provavelmente em S\u00e3o Paulo. <\/font><font size=\"3\" face=\"Arial\">Em pauta, as coliga\u00e7\u00f5es do partido em 2018 e a rela\u00e7\u00e3o com os peemedebistas. <\/font><font size=\"3\" face=\"Arial\">O discurso anti-golpistas j\u00e1 come\u00e7ou a perder for\u00e7a, com as b\u00ean\u00e7\u00e3os de Lula. <\/font><font size=\"3\" face=\"Arial\">Em pelo menos cinco estados, h\u00e1 fortes chances de PT e PMDB caminharem juntos \u2013 Minas Gerais, Paran\u00e1, Par\u00e1, Alagoas e Cear\u00e1. <\/font><font size=\"3\" face=\"Arial\">No plano nacional, prioridade \u00e9 tentar atrair o PSB para o palanque de Lula ou de Haddad, caso o ex-presidente seja impedido de concorrer. <\/font><font size=\"3\" face=\"Arial\">A tarefa \u00e9 dific\u00edlima, j\u00e1 que o PSB est\u00e1 em avan\u00e7adas negocia\u00e7\u00f5es para ter Joaquim Barbosa na cabe\u00e7a da chapa presidencial. <strong><font size=\"2\">Fonte: Blog do Magno Martins<\/font><\/strong><\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>O PT far\u00e1 uma reuni\u00e3o da Executiva e do Diret\u00f3rio nacionais na semana que vem, provavelmente em S\u00e3o Paulo. Em pauta, as coliga\u00e7\u00f5es do partido em 2018 e a rela\u00e7\u00e3o com os peemedebistas. O discurso anti-golpistas j\u00e1 come\u00e7ou a perder for\u00e7a, com as b\u00ean\u00e7\u00e3os de Lula. Em pelo menos cinco estados, h\u00e1 fortes chances de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3756","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/3756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=3756"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/3756\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=3756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=3756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=3756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}