{"id":3749,"date":"2017-12-02T21:30:00","date_gmt":"2017-12-02T21:30:00","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2017\/12\/02\/aniversariante-do-dia-joel-silva-um-dos-maiores-comunicadores-do-agreste\/"},"modified":"2017-12-02T21:30:00","modified_gmt":"2017-12-02T21:30:00","slug":"aniversariante-do-dia-joel-silva-um-dos-maiores-comunicadores-do-agreste","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/aniversariante-do-dia-joel-silva-um-dos-maiores-comunicadores-do-agreste\/","title":{"rendered":"ANIVERSARIANTE DO DIA: JOEL SILVA, UM DOS MAIORES COMUNICADORES DA REGI\u00c3O"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/site_d99d9491626c3a49519418cb02d34a59.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Site\" style=\"border-top: 0px; border-right: 0px; background-image: none; border-bottom: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 0px auto 10px; border-left: 0px; display: block; padding-right: 0px\" border=\"0\" alt=\"Site\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/site_thumb_2c6238ff30fc64755d4720f5f3848c82.jpg\" width=\"1462\" height=\"1097\"><\/a>O dia de hoje \u00e9 muito especial para o maior locutor de carro de som de toda a regi\u00e3o do Agreste Meridional, Sr. Joel Silva, popularmente conhecido como Joel Locutor. Considerado atualmente como um dos melhores comunicadores de Pernambuco, vem atuando em benef\u00edcio das fam\u00edlias saloaenses h\u00e1 d\u00e9cadas, deixando sua marca em todos os eventos que participa. Joel \u00e9 um profissional altamente capacitado e competente e \u00e9 desejado por v\u00e1rios grupos pol\u00edticos da cidade.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Silva \u00e9 muito carism\u00e1tico e conseguiu ao longo dos anos o respeito dos moradores de seu munic\u00edpio, sempre com sua forma simples e objetiva de se fazer comunica\u00e7\u00e3o. Ainda jovem atuou em diversas campanhas politicas, al\u00e9m de ser animador de pegas de boi, vaquejadas e torneios de futebol. Foi professor de educa\u00e7\u00e3o f\u00edsica da escola S\u00e3o Vicente e tamb\u00e9m atleta de times de Salo\u00e1\/PE. Joel tamb\u00e9m foi secret\u00e1rio de governo em v\u00e1rias administra\u00e7\u00f5es, dentre elas dos prefeitos An\u00edsio Godoy, Ubirajara Barbosa e Rivaldo Alves de Souza.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Como diriam os mais tradicionais: UM EVENTO EM SALO\u00c1 SEM JOEL, N\u00c3O TEM GRA\u00c7A ! Podemos dizer com toda convic\u00e7\u00e3o que Joel Silva \u00e9 o professor dos locutores de Salo\u00e1, ou seja, tudo come\u00e7ou com ele. Por isso e muito mais, gostar\u00edamos de prestar esta simples homenagem ao nosso querido Joel Silva, que muito orgulho tem dado aos saloaenses, com sua forma carinhosa de trabalhar e de tratar as pessoas. Parab\u00e9ns, Joel Silva\u2026 muitas felicidades e muitos anos de vida !!!<\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>O dia de hoje \u00e9 muito especial para o maior locutor de carro de som de toda a regi\u00e3o do Agreste Meridional, Sr. Joel Silva, popularmente conhecido como Joel Locutor. Considerado atualmente como um dos melhores comunicadores de Pernambuco, vem atuando em benef\u00edcio das fam\u00edlias saloaenses h\u00e1 d\u00e9cadas, deixando sua marca em todos os eventos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3749","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/3749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=3749"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/3749\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=3749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=3749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=3749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}