{"id":32722,"date":"2026-09-01T20:49:39","date_gmt":"2026-09-01T23:49:39","guid":{"rendered":"https:\/\/www.saloanoticias.com\/v1\/?p=32722"},"modified":"2026-09-01T22:30:46","modified_gmt":"2026-09-02T01:30:46","slug":"morre-aos-73-anos-erasmo-rodrigues-pereira-ex-diretor-da-cadeia-publica-de-saloa","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/morre-aos-73-anos-erasmo-rodrigues-pereira-ex-diretor-da-cadeia-publica-de-saloa\/","title":{"rendered":"Morre aos 73 anos Erasmo Rodrigues Pereira, ex-diretor da Cadeia P\u00fablica de Salo\u00e1"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Faleceu na noite desta ter\u00e7a-feira (1\u00ba), no Hospital Perp\u00e9tuo Socorro, em Garanhuns, Erasmo Rodrigues Pereira, aos 73 anos de idade, ex-diretor da Cadeia P\u00fablica de Salo\u00e1. Segundo informa\u00e7\u00f5es preliminares, Erasmo teria sofrido um infarto. A causa, no entanto, ainda n\u00e3o foi oficialmente confirmada pela fam\u00edlia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erasmo era bastante conhecido em Salo\u00e1 e tinha uma trajet\u00f3ria marcada pela atua\u00e7\u00e3o \u00e0 frente da Cadeia P\u00fablica do munic\u00edpio. Ele era casado com Eliana Ferreira, suplente de vereadora de Salo\u00e1. O vel\u00f3rio ser\u00e1 realizado no audit\u00f3rio da Escola S\u00e3o Vicente, em Salo\u00e1, at\u00e9 \u00e0s 10h, depois ser\u00e1 levado para o cemit\u00e9rio Morada da Paz em Recife onde ser\u00e1 sepultado nesta quarta-feira (2). Familiares, amigos e membros da comunidade poder\u00e3o prestar as \u00faltimas homenagens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O hor\u00e1rio e o local do sepultamento ainda ser\u00e3o informados pela fam\u00edlia. O falecimento de Erasmo Rodrigues Pereira deixa familiares, amigos e conhecidos consternados, especialmente aqueles que acompanharam sua trajet\u00f3ria pessoal e profissional no munic\u00edpio.<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Faleceu na noite desta ter\u00e7a-feira (1\u00ba), no Hospital Perp\u00e9tuo Socorro, em Garanhuns, Erasmo Rodrigues Pereira, aos 73 anos de idade, ex-diretor da Cadeia P\u00fablica de Salo\u00e1. Segundo informa\u00e7\u00f5es preliminares, Erasmo teria sofrido um infarto. A causa, no entanto, ainda n\u00e3o foi oficialmente confirmada pela fam\u00edlia. Erasmo era bastante conhecido em Salo\u00e1 e tinha uma trajet\u00f3ria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[22],"class_list":["post-32722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-dia","tag-destaques"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/32722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=32722"}],"version-history":[{"count":2,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/32722\/revisions"}],"predecessor-version":[{"id":32726,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/32722\/revisions\/32726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media\/32723"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=32722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=32722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=32722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}