{"id":16070,"date":"2021-10-07T22:17:15","date_gmt":"2021-10-08T01:17:15","guid":{"rendered":"https:\/\/www.saloanoticias.com\/v1\/?p=16070"},"modified":"2021-10-09T08:45:14","modified_gmt":"2021-10-09T11:45:14","slug":"pernambuco-segue-reduzindo-numero-de-homicidios-em-2021","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/pernambuco-segue-reduzindo-numero-de-homicidios-em-2021\/","title":{"rendered":"Pernambuco segue reduzindo os n\u00fameros de homic\u00eddios em 2021"},"content":{"rendered":"\n<p>O governador Paulo C\u00e2mara conduziu, nesta quarta-feira (06.10), a reuni\u00e3o do Pacto pela Vida (PPV) que avaliou as a\u00e7\u00f5es e estat\u00edsticas da seguran\u00e7a p\u00fablica em 2021. Entre janeiro e setembro deste ano, em compara\u00e7\u00e3o com o mesmo per\u00edodo de 2020, houve um recuo de 12% no n\u00famero de homic\u00eddios. Os crimes patrimoniais tamb\u00e9m apresentaram uma retra\u00e7\u00e3o de aproximadamente 4%. Os n\u00fameros oficiais ser\u00e3o divulgados no pr\u00f3ximo dia 15.<\/p>\n\n\n\n<p>\u201cOs resultados s\u00e3o importantes. Mas a reuni\u00e3o tamb\u00e9m buscou planejar os pr\u00f3ximos tr\u00eas meses e pactuar a\u00e7\u00f5es necess\u00e1rias, porque nossa meta \u00e9 continuar reduzindo a viol\u00eancia em Pernambuco, mostrando cada vez mais que o caminho conduzido pelo Pacto Pela Vida \u00e9 um caminho da paz e de salvar vidas\u201d, pontuou Paulo C\u00e2mara.<\/p>\n\n\n\n<p>Durante o encontro, o governador assinou autoriza\u00e7\u00e3o de or\u00e7amento, no valor de R$ 9 milh\u00f5es, para aquisi\u00e7\u00e3o de quatro mil novas pistolas Beretta 9mm, com o objetivo de renovar o armamento das pol\u00edcias de Pernambuco. As pistolas, incluindo carregadores, s\u00e3o de fabrica\u00e7\u00e3o italiana e ser\u00e3o adquiridas com recursos pr\u00f3prios do Estado, por meio de ades\u00e3o a uma ata de registro de pre\u00e7os da Secretaria Nacional de Seguran\u00e7a P\u00fablica, vinculada ao Minist\u00e9rio da Justi\u00e7a. A previs\u00e3o que as armas sejam entregues no in\u00edcio do pr\u00f3ximo ano.<\/p>\n\n\n\n<p>\u201cS\u00e3o equipamentos mais leves e modernos, dentro do que h\u00e1 de melhor sendo utilizado pelas for\u00e7as de seguran\u00e7a no mundo. Mas \u00e9 preciso esclarecer que a repress\u00e3o e o enfrentamento s\u00e3o o \u00faltimo recurso. A prioridade da seguran\u00e7a, e de todos os que fazem o Pacto pela Vida, \u00e9 a preven\u00e7\u00e3o e preserva\u00e7\u00e3o de vidas\u201d, afirmou o secret\u00e1rio de Defesa Social do Estado, Humberto Freire.<\/p>\n\n\n\n<p>Participaram presencialmente do encontro os secret\u00e1rios Alexandre Rebelo (Planejamento e Gest\u00e3o), Cloves Benevides (Preven\u00e7\u00e3o \u00e0 viol\u00eancia e \u00e0s Drogas), Pedro Eurico (Justi\u00e7a e Direitos Humanos), Ana Elisa Gadelha (Mulher) e Carlos Jos\u00e9 (Chefe da Casa Militar); a gerente geral da Pol\u00edcia cient\u00edfica, Sandra Santos; o comandante da Pol\u00edcia Militar, Roberto Santana; o comandante do Corpo de Bombeiros, Rog\u00e9rio Coutinho; e o chefe da Pol\u00edcia Civil, Nehemias Falc\u00e3o.<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>O governador Paulo C\u00e2mara conduziu, nesta quarta-feira (06.10), a reuni\u00e3o do Pacto pela Vida (PPV) que avaliou as a\u00e7\u00f5es e estat\u00edsticas da seguran\u00e7a p\u00fablica em 2021. Entre janeiro e setembro deste ano, em compara\u00e7\u00e3o com o mesmo per\u00edodo de 2020, houve um recuo de 12% no n\u00famero de homic\u00eddios. Os crimes patrimoniais tamb\u00e9m apresentaram uma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[22],"class_list":["post-16070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-destaques"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/16070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=16070"}],"version-history":[{"count":3,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/16070\/revisions"}],"predecessor-version":[{"id":16078,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/16070\/revisions\/16078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media\/16074"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=16070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=16070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=16070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}