{"id":1536,"date":"2014-12-28T16:00:00","date_gmt":"2014-12-28T16:00:00","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2014\/12\/28\/dica-de-cinema-exodus\/"},"modified":"2014-12-28T16:00:00","modified_gmt":"2014-12-28T16:00:00","slug":"dica-de-cinema-exodus","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/dica-de-cinema-exodus\/","title":{"rendered":"DICA DE CINEMA  &#8211;  \u00caXODUS"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/10888719_742111105880182_4140905470210853732_n_634fbdf524ab0d925ae6d7f853a58576.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"10888719_742111105880182_4140905470210853732_n\" style=\"border-top: 0px; border-right: 0px; background-image: none; border-bottom: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 0px auto 10px; border-left: 0px; display: block; padding-right: 0px\" border=\"0\" alt=\"10888719_742111105880182_4140905470210853732_n\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/10888719_742111105880182_4140905470210853732_n_thumb_7c4f7510d84301e19dd5588b1187fe30.jpg\" width=\"597\" height=\"354\"><\/a>H\u00e1 58 anos, a aud\u00e1cia do produtor Cecil B. DeMille dava ao mundo o \u00e9pico religioso &#8220;Os Dez Mandamentos&#8221;. Com suas 3h40min de dura\u00e7\u00e3o, a produ\u00e7\u00e3o elevou ao estrelato o ator Charton Helston, que protagonizava o filme, na pele do b\u00edblico Mois\u00e9s. Lan\u00e7ado em outubro de 1956, o filme tornaria-se a grande refer\u00eancia como obra do g\u00eanero, muito pela beleza impressionante de seus efeitos especiais, lhe rendendo um Oscar no ano seguinte, e garantindo que o filme de DeMille voltasse a entrar em cartaz pelos 20 anos seguintes, todo dezembro ou na Semana Santa, quase como uma obriga\u00e7\u00e3o na agenda das salas de cinema do Pa\u00eds cat\u00f3lico.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Hoje, Hollywood oferece uma outra (e bem contempor\u00e2nea) leitura para a hist\u00f3ria do profeta hebreu que libertou seu povo de centenas de anos de escravid\u00e3o sob o julgo do reinado eg\u00edpicio por v\u00e1rias gera\u00e7\u00f5es no Antigo Egito. A miss\u00e3o de con ceber o novo desenho, de &#8220;\u00caxodo: Deuses e Reis&#8221; (&#8220;Exodus: Gods and Kings&#8221;, EUA, 2014) recaiu sobre as m\u00e3os de Ridley Scott, cineasta ingl\u00eas sempre observado pelo conhecido refinamento visual de suas obras &#8211; &#8220;Alien&#8221;, &#8220;Blade Runner&#8221;, &#8220;1492&#8221;, &#8220;Gladiador&#8221;.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Scott e sua equipe criativa n\u00e3o nos decepciona, oferecendo um trabalho de encher os olhos em todos os aspectos t\u00e9cnicos que costumam chamar a aten\u00e7\u00e3o em filme hist\u00f3ricos &#8211; loca\u00e7\u00e3o, cenografia, figurino, dire\u00e7\u00e3o de arte, etc. O desenho de produ\u00e7\u00e3o de &#8220;\u00caxodo&#8221; \u00e9 um espet\u00e1culo \u00e0 parte, com as imagens &#8211; mesmo que simuladas por computador &#8211; imprimindo na tela uma bela ideia pl\u00e1stica de como seria a din\u00e2mica de um Egito comandado pelo rei Rams\u00e9s (Joe Edgerton) com todos os seus constrastes de riqueza e mis\u00e9ria.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Ao contr\u00e1rio das boas qualidades apontadas acima, a trilha sonora de Alberto Iglesias \u00e9 discreta demais, ou tradicional demais, n\u00e3o dando a atmosfera grandiloquente que se espera de a\u00e7\u00f5es como a abertura do Mar Vermelho por Mois\u00e9s.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Mas, assim como &#8220;No\u00e9&#8221;, de Darren Aronofsky, em 2013, o mais radical &#8211; no mau sentido &#8211; em &#8220;\u00caxodo&#8221; est\u00e1 na proposta que seu roteiro &#8211; escrito a quatro m\u00e3os por Adam Cooper, Bill Collage, Jeffrey Caine e Steven Zaillian &#8211; nos \u00e9 oferecido. Isto porque aqui refer\u00eancias milenares como a pr\u00f3pria abertura do Mar Vermelho n\u00e3o acontece associada ao cajado de Mois\u00e9s, muito menos vemos as escrituras das duas t\u00e1buas dos Dez Mandamentos acontecerem de maneira espetacular, mediadas por uma interven\u00e7\u00e3o clim\u00e1tica.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">As pragas divinas que aterrorizam o fara\u00f3 Rams\u00e9s &#8211; as \u00e1guas ensanguentadas, a infesta\u00e7\u00e3o de r\u00e3s, a doen\u00e7a nos animais, a invas\u00e3o de gafanhotos, entre outras, al\u00e9m da morte dos primog\u00eanitos &#8211; tamb\u00e9m ganham uma explica\u00e7\u00e3o l\u00f3gica pelo s\u00e1bio do fara\u00f3. N\u00e3o menos adequada \u00e0 raz\u00e3o hollywo &#8211; odiana &#8211; e contra a f\u00e9 pregada no enredo b\u00edblico -, es &#8211; t\u00e1 a vis\u00e3o de Moises (Christina Bale) ao encarar o Todo- Poderoso na Montanha Proibida. A vis\u00e3o se d\u00e1 ap\u00f3s o profeta acordar de uma acidente no qual teve a cabe\u00e7a atingida por uma pe dra. Deus aparece, a prop\u00f3sito, na pele de um menino (Isaac Andrews).<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">A op\u00e7\u00e3o \u00e9 curiosa e, de certa forma, n\u00e3o empresta aos di\u00e1logos entre Ele e Mois\u00e9s a solenidade que se espera. Bale e os outros atores (com exce\u00e7\u00e3o de Edgerton) tamb\u00e9m n\u00e3o parecem representar a dimens\u00e3o e a profundidade que a hist\u00f3ria pede. Em resumo, h\u00e1 em &#8220;\u00ca &#8211; xo do&#8221; um esfor\u00e7o para deixar a hist\u00f3ria do segundo livro do Antigo Testamento qua se com um vi\u00e9s laico. N\u00e3o deixa de ser uma estra &#8211; t\u00e9gia corajosa, visando agradar a maior parte dos espectadores independentes de sua cren\u00e7a (ou descren\u00e7a religiosa). Mas tamb\u00e9m n\u00e3o deixa de ser covarde, pelo mesmo motivo.<\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>H\u00e1 58 anos, a aud\u00e1cia do produtor Cecil B. DeMille dava ao mundo o \u00e9pico religioso &#8220;Os Dez Mandamentos&#8221;. Com suas 3h40min de dura\u00e7\u00e3o, a produ\u00e7\u00e3o elevou ao estrelato o ator Charton Helston, que protagonizava o filme, na pele do b\u00edblico Mois\u00e9s. Lan\u00e7ado em outubro de 1956, o filme tornaria-se a grande refer\u00eancia como obra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1536","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=1536"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1536\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=1536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=1536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=1536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}