{"id":1356,"date":"2014-10-09T01:18:36","date_gmt":"2014-10-09T01:18:36","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2014\/10\/09\/acaba-de-falecer-no-recife-dona-zulmira\/"},"modified":"2014-10-09T01:18:36","modified_gmt":"2014-10-09T01:18:36","slug":"acaba-de-falecer-no-recife-dona-zulmira","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/acaba-de-falecer-no-recife-dona-zulmira\/","title":{"rendered":"ZULMIRA BIRUNDA FALECEU NO RECIFE NA NOITE DESTA QUARTA-FEIRA (8)"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/desfiledsc_4376_0be9a83892028d0da3c6f39c93152889.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"desfileDSC_4376\" style=\"border-left-width: 0px; border-right-width: 0px; background-image: none; border-bottom-width: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 0px auto 10px; display: block; padding-right: 0px; border-top-width: 0px\" border=\"0\" alt=\"desfileDSC_4376\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/desfiledsc_4376_thumb_eba2efe4056fb633773df61869fc084c.jpg\" width=\"482\" height=\"319\"><\/a>Acaba de falecer na capital do Estado aos 96 anos, Dona Zulmira Alves de Souza, mais conhecida como Dona Zulmira Birunda, esposa do saudoso Ant\u00f4nio Alves de Souza (Ant\u00f4nio Ricardo). Ela estava internada na UTI do Hospital Portugu\u00eas h\u00e1 mais de 30 dias e veio a \u00f3bito \u00e0s 8:30 horas desta quarta-feira (8). Segundo as primeiras informa\u00e7\u00f5es que temos ela sofreu uma parada card\u00edaca, foi reanimada pelos m\u00e9dicos e logo em seguida sofreu outra parada e n\u00e3o resistiu. A fam\u00edlia j\u00e1 est\u00e1 no hospital providenciando a documenta\u00e7\u00e3o para transferir o corpo para Salo\u00e1, local onde ser\u00e1 sepultada.<\/font><\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">O vel\u00f3rio acontecer\u00e1 no audit\u00f3rio da escola S\u00e3o Vicente e o sepultamento acontecer\u00e1 \u00e0s 5 da tarde no cemit\u00e9rio Santa Quit\u00e9ria em Salo\u00e1\/PE nesta quinta (9). Dona Zulmira era esposa do primeiro prefeito de Salo\u00e1, Ant\u00f4nio Ricardo e era conhecida por sua sublime hospitalidade e recebia todos em sua resid\u00eancia com muito respeito e carinho. Ela \u00e9 m\u00e3e do ex-prefeito Rivaldo Alves, do ex-deputado Manoel Alves e av\u00f3 do atual prefeito Ricardo Alves. Em menos de um m\u00eas faleceu duas senhoras que fizeram parte da hist\u00f3ria de Salo\u00e1\/PE, Dona Dulce, primeira secret\u00e1ria do munic\u00edpio e Dona Zulmira, primeira dama, esposa do primeira prefeito desta terra.<\/font><\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">O prefeito Ricardo Alves anunciou luto de tr\u00eas dias pela morte de Dona Zulmira. Fica somente a saudade dos parentes e amigos desta mulher simples e guerreira que entra para a hist\u00f3ria desta cidade. Os que fazem o Blog Salo\u00e1 Not\u00edcias desejam as condol\u00eancias para todos os familiares.<\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Acaba de falecer na capital do Estado aos 96 anos, Dona Zulmira Alves de Souza, mais conhecida como Dona Zulmira Birunda, esposa do saudoso Ant\u00f4nio Alves de Souza (Ant\u00f4nio Ricardo). Ela estava internada na UTI do Hospital Portugu\u00eas h\u00e1 mais de 30 dias e veio a \u00f3bito \u00e0s 8:30 horas desta quarta-feira (8). Segundo as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1356","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=1356"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1356\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=1356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=1356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}