{"id":1345,"date":"2014-10-05T23:07:57","date_gmt":"2014-10-05T23:07:57","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2014\/10\/05\/paulo-camara-e-o-novo-governador-de-pernambuco\/"},"modified":"2014-10-05T23:07:57","modified_gmt":"2014-10-05T23:07:57","slug":"paulo-camara-e-o-novo-governador-de-pernambuco","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/paulo-camara-e-o-novo-governador-de-pernambuco\/","title":{"rendered":"PAULO C\u00c2MARA \u00c9 O NOVO GOVERNADOR DE PERNAMBUCO"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/e1a0bffec5f4f06ae1ee912cad2f070f.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"e1a0bffec5f4f06ae1ee912cad2f070f\" style=\"border-top: 0px; border-right: 0px; background-image: none; border-bottom: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 0px auto 10px; border-left: 0px; display: block; padding-right: 0px\" border=\"0\" alt=\"e1a0bffec5f4f06ae1ee912cad2f070f\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/e1a0bffec5f4f06ae1ee912cad2f070f_thumb.jpg\" width=\"434\" height=\"236\"><\/a>Com 69,79% das urnas apuradas, Pernambuco j\u00e1 escolheu o seu novo representante na noite deste domingo (5). Candidato pelo Partido Socialista Brasileiro (PSB), Paulo C\u00e2mara foi eleito com 2.057,854 de votos, 67,64% dos votos v\u00e1lidos. O segundo colocado foi Armando Monteiro, candidato do Partido Trabalhista Brasileiro (PTB), com 960.166 de votos (31,56% dos votos v\u00e1lidos). Z\u00e9 Gomes, do Partido Socialismo e Liberdade (PSOL), foi o terceiro, com 17 mil votos. As informa\u00e7\u00f5es foram atualizadas at\u00e9 19h37.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Nascido em 1972, na capital pernambucana, Paulo Henrique Saraiva C\u00e2mara \u00e9 formado em Ci\u00eancias Econ\u00f4micas, p\u00f3s graduado em Contabilidade e Controladoria Governamental e mestre em Gest\u00e3o P\u00fablica, todos pela Universidade Federal de Pernambuco (UFPE). Na carreira pol\u00edtica, assumiu a Secretaria de Administra\u00e7\u00e3o de 2007 a dezembro de 2010, quando passou para a pasta do Turismo. No m\u00eas seguinte, assumiu o cargo de Secret\u00e1rio da Fazenda.<\/font> <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Apesar de filiado ao PSB apenas em outubro de 2013, Paulo C\u00e2mara superou todos os concorrentes ainda no primeiro turno. A ascens\u00e3o do ex-secretario da Fazenda se deve muito ao apoio de Eduardo Campos, ex-governador de Pernambuco e morto no dia 13 de agosto, em um acidente a\u00e9reo na cidade de Santos. <\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Com 69,79% das urnas apuradas, Pernambuco j\u00e1 escolheu o seu novo representante na noite deste domingo (5). Candidato pelo Partido Socialista Brasileiro (PSB), Paulo C\u00e2mara foi eleito com 2.057,854 de votos, 67,64% dos votos v\u00e1lidos. O segundo colocado foi Armando Monteiro, candidato do Partido Trabalhista Brasileiro (PTB), com 960.166 de votos (31,56% dos votos v\u00e1lidos). [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1345","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=1345"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1345\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=1345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=1345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=1345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}