{"id":1320,"date":"2014-09-26T18:23:00","date_gmt":"2014-09-26T18:23:00","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2014\/09\/26\/ze-carlos-do-riachao-sai-do-grupo-gp-e-vem-para-situacao\/"},"modified":"2014-09-26T18:23:00","modified_gmt":"2014-09-26T18:23:00","slug":"ze-carlos-do-riachao-sai-do-grupo-gp-e-vem-para-situacao","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/ze-carlos-do-riachao-sai-do-grupo-gp-e-vem-para-situacao\/","title":{"rendered":"Z\u00c9 CARLOS DO RIACH\u00c3O SAI DO GRUPO GP E VEM PARA A SITUA\u00c7\u00c3O TAMB\u00c9M"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/z-carlos-do-riacho-n.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Z&eacute; Carlos do Riach&atilde;o n\" style=\"border-top: 0px; border-right: 0px; background-image: none; border-bottom: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 0px auto 10px; border-left: 0px; display: block; padding-right: 0px\" border=\"0\" alt=\"Z&eacute; Carlos do Riach&atilde;o n\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/z-carlos-do-riacho-n_thumb.jpg\" width=\"497\" height=\"373\"><\/a>Z\u00e9 Carlos do Riach\u00e3o agora faz parte do grupo Caf\u00e9 com Leite da cidade de Salo\u00e1. A informa\u00e7\u00e3o foi repassada a poucos instantes por assessores do prefeito Ricardo juntamente com esta foto. Z\u00e9 Carlos era a \u00fanica lideran\u00e7a pol\u00edtica de toda aquela regi\u00e3o que ainda n\u00e3o estava no palanque do grupo da situa\u00e7\u00e3o. Como j\u00e1 hav\u00edamos divulgado em mat\u00e9rias anteriormente, o Grupo GP perdeu nas \u00faltimas semanas quase todos os seus cabos eleitorais e lideran\u00e7as pol\u00edticas em todo o munic\u00edpio, estes que votaram e pediram votos para Danilo Pereira na elei\u00e7\u00e3o de 2012.<\/font><\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">O desmonte do Grupo GP \u00e9 grande e j\u00e1 \u00e9 poss\u00edvel dizer que compromete uma poss\u00edvel candidatura para a elei\u00e7\u00e3o de 2016. Informa\u00e7\u00f5es chegam a todo momento dando conta de que os poucos correligion\u00e1rios do Grupo GP que ainda restam est\u00e3o bastante preocupados com o futuro incerto deles. Um coisa \u00e9 certa, Ricardo Alves e seus aliados minaram definitivamente o grupo da oposi\u00e7\u00e3o, os deixando quase que sem l\u00edderes nas comunidades. O assessor que nos passou estas informa\u00e7\u00f5es disse que ainda tem mais pol\u00edticos que estar\u00e3o no palanque do Caf\u00e9 com Leite nos pr\u00f3ximos dias.<\/font><\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">A sa\u00edda de Z\u00e9 Carlos do Riach\u00e3o vai gerar muitos coment\u00e1rios por todo o munic\u00edpio, pois ele era uma pessoa bastante ligada ao ex-prefeito Gilvan Pereira e era quem coordenava os trabalho da prefeitura na comunidade em que ele mora.<\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Z\u00e9 Carlos do Riach\u00e3o agora faz parte do grupo Caf\u00e9 com Leite da cidade de Salo\u00e1. A informa\u00e7\u00e3o foi repassada a poucos instantes por assessores do prefeito Ricardo juntamente com esta foto. Z\u00e9 Carlos era a \u00fanica lideran\u00e7a pol\u00edtica de toda aquela regi\u00e3o que ainda n\u00e3o estava no palanque do grupo da situa\u00e7\u00e3o. Como j\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1320","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=1320"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1320\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=1320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=1320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=1320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}