{"id":1304,"date":"2014-09-21T11:00:00","date_gmt":"2014-09-21T11:00:00","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2014\/09\/21\/informe-da-justica-eleitoral-de-saloa-pe\/"},"modified":"2014-09-21T11:00:00","modified_gmt":"2014-09-21T11:00:00","slug":"informe-da-justica-eleitoral-de-saloa-pe","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/informe-da-justica-eleitoral-de-saloa-pe\/","title":{"rendered":"INFORME DA JUSTI\u00c7A ELEITORAL DE SALO\u00c1"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/140327071528_justia-eleitoral_aa2bda72fd4a828c3a1367a640736192.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"140327071528_justi&Ccedil;a-eleitoral\" style=\"border-top: 0px; border-right: 0px; background-image: none; border-bottom: 0px; float: left; padding-top: 0px; padding-left: 0px; margin: 5px 5px 10px 0px; border-left: 0px; display: inline; padding-right: 0px\" border=\"0\" alt=\"140327071528_justi&Ccedil;a-eleitoral\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/140327071528_justia-eleitoral_thumb_092c4590a46565f05da949bde128d411.jpg\" width=\"251\" align=\"left\" height=\"193\"><\/a>O Dr. Eliziongerber de Freitas, Juiz Eleitoral da 136\u00aa Zona, informa aos eleitores estudantes da necessidade de possu\u00edrem um documento oficial com fotos com vista votarem nas elei\u00e7\u00f5es de 2014. A Justi\u00e7a Eleitoral est\u00e1 em campanha institucional no sentido de todos os eleitores que ainda n\u00e3o tenham RG ou Carteira de Trabalho solicitem, o quanto antes, na prefeitura de Salo\u00e1 ou no Expresso Cidad\u00e3o em Garanhuns. A Lei 9504\/97, Lei das Elei\u00e7\u00f5es, no Art. 91-A, reza que \u201cno momento da vota\u00e7\u00e3o, al\u00e9m do respectivo t\u00edtulo, o eleitor dever\u00e1 apresentar documento de identifica\u00e7\u00e3o com fotografia\u201d.<\/font><\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">Impede salientar que o t\u00edtulo n\u00e3o \u00e9 obrigat\u00f3rio, enquanto que o documento oficial com fotografia \u00e9 indispens\u00e1vel. Com o fim de dar conhecimento os \u00fanicos documentos aptos para votar s\u00e3o: Carteira de Identidade, Carteira Nacional de Habilita\u00e7\u00e3o, Carteira de Trabalho, Certificado de Reservista, Passaporte e Carteira de Categoria Profissional Reconhecida por Lei.<\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>O Dr. Eliziongerber de Freitas, Juiz Eleitoral da 136\u00aa Zona, informa aos eleitores estudantes da necessidade de possu\u00edrem um documento oficial com fotos com vista votarem nas elei\u00e7\u00f5es de 2014. A Justi\u00e7a Eleitoral est\u00e1 em campanha institucional no sentido de todos os eleitores que ainda n\u00e3o tenham RG ou Carteira de Trabalho solicitem, o quanto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1304","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=1304"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1304\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=1304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=1304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=1304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}