{"id":1281,"date":"2014-09-10T22:28:23","date_gmt":"2014-09-10T22:28:23","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2014\/09\/10\/datafolha-paulo-camara-39-e-armadno-monteiro-33\/"},"modified":"2014-09-10T22:28:23","modified_gmt":"2014-09-10T22:28:23","slug":"datafolha-paulo-camara-39-e-armadno-monteiro-33","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/datafolha-paulo-camara-39-e-armadno-monteiro-33\/","title":{"rendered":"C\u00c2MARA 39% E ARMANDO MONTEIRO 33%, DIZ DATAFOLHA"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/10390566_666660513429480_2878984137602165217_n.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"10390566_666660513429480_2878984137602165217_n\" style=\"border-top: 0px; border-right: 0px; background-image: none; border-bottom: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 0px auto 10px; border-left: 0px; display: block; padding-right: 0px\" border=\"0\" alt=\"10390566_666660513429480_2878984137602165217_n\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/10390566_666660513429480_2878984137602165217_n_thumb.jpg\" width=\"486\" height=\"324\"><\/a>Pesquisa Datafolha divulgada nesta quarta-feira (10) aponta os seguintes percentuais de inten\u00e7\u00e3o de voto na corrida para o governo de Pernambuco: Paulo C\u00e2mara tem 39% e Armando Monteiro, 33%, aponta Datafolha. Margem de erro \u00e9 de tr\u00eas pontos percentuais, para mais ou para menos. Instituto entrevistou 1.211 eleitores entre 8 e 9 de setembro. <\/font><font size=\"3\" face=\"Arial\">Pesquisa Datafolha divulgada nesta quarta-feira (10) aponta os seguintes percentuais de inten\u00e7\u00e3o de voto na corrida para o governo de Pernambuco:<\/font><\/p>\n<p><font size=\"3\" face=\"Arial\"> <\/p>\n<p align=\"center\"><\/font><a href=\"http:\/\/g1.globo.com\/politica\/politico\/paulo-camara.html\"><font size=\"5\" face=\"Arial\"><strong>Paulo C\u00e2mara<\/strong><\/font><\/a><font size=\"5\" face=\"Arial\"><strong> (PSB): 39%<br \/><\/strong><\/font><a href=\"http:\/\/g1.globo.com\/politica\/politico\/armando-monteiro.html\"><font size=\"5\" face=\"Arial\"><strong>Armando Monteiro<\/strong><\/font><\/a><font size=\"5\" face=\"Arial\"><strong> (PTB): 33%<br \/><\/strong><\/font><a href=\"http:\/\/g1.globo.com\/politica\/politico\/jose-gomes-de-sa-neto.html\"><font size=\"4\" face=\"Arial\"><strong>Z\u00e9 Gomes<\/strong><\/font><\/a><font size=\"4\" face=\"Arial\"><strong> (PSOL): 1%<br \/><\/strong><\/font><a href=\"http:\/\/g1.globo.com\/politica\/politico\/miguel-anacleto.html\"><font size=\"4\" face=\"Arial\"><strong>Miguel Anacleto<\/strong><\/font><\/a><font size=\"4\" face=\"Arial\"><strong> (PCB): 1%<br \/><\/strong><\/font><a href=\"http:\/\/g1.globo.com\/politica\/politico\/pantaleao.html\"><font size=\"4\" face=\"Arial\"><strong>Pantale\u00e3o<\/strong><\/font><\/a><font size=\"4\" face=\"Arial\"><strong> (PCO): 0%<br \/><\/strong><\/font><a href=\"http:\/\/g1.globo.com\/politica\/politico\/jair-pedro.html\"><font size=\"4\" face=\"Arial\"><strong>Jair Pedro<\/strong><\/font><\/a><font size=\"4\" face=\"Arial\"><strong> (PSTU): 0%<br \/>Brancos e nulos: 9%<br \/>N\u00e3o souberam responder: 16%<\/strong><\/font><\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">A pesquisa foi encomendada pela TV Globo. <\/font><a href=\"http:\/\/g1.globo.com\/pernambuco\/eleicoes\/2014\/noticia\/2014\/09\/datafolha-mostra-armando-e-paulo-empatados-com-36-em-pernambuco.html\"><font size=\"3\" face=\"Arial\">No levantamento anterior, realizado pelo instituto nos dias 2 e 3 de setembro, Paulo e Armando tinham 36% das inten\u00e7\u00f5es de voto<\/font><\/a><font size=\"3\" face=\"Arial\">. Realizada entre os dias 8 e 9 de setembro, a pesquisa contou com entrevistas de 1.211 entrevistas em 43 munic\u00edpios. A margem de erro \u00e9 de tr\u00eas pontos percentuais, para mais ou para menos. O n\u00edvel de confian\u00e7a \u00e9 de 95%, o que quer dizer que, se levada em conta a margem de erro de dois pontos para mais ou para menos, a probabilidade de o resultado retratar a realidade \u00e9 de 95%.<\/font>  <\/p>\n<p align=\"center\"><font size=\"3\" face=\"Arial\">A pesquisa est\u00e1 registrada no Tribunal Regional Eleitoral (TRE) sob o protocolo n\u00famero PE-00023\/2014 e no Tribunal Superior Eleitoral (TSE) sob protocolo n\u00famero BR-00584\/2014. <strong>Segundo turno&nbsp; &#8211;&nbsp; <\/strong>O Datafolha fez uma simula\u00e7\u00e3o de segundo turno entre Paulo C\u00e2mara e Armando Monteiro. Os resultados s\u00e3o os seguintes:<br \/><\/font><font face=\"Arial\"><font size=\"3\"><strong><font size=\"4\">Paulo C\u00e2mara (PSB): 43%<br \/>Armando Monteiro (PTB): 37%<br \/>Brancos e nulos: 10%<br \/>Indecisos: 11%<br \/><\/font>Rejei\u00e7\u00e3o<\/strong><br \/>O Datafolha tamb\u00e9m apontou a rejei\u00e7\u00e3o dos candidatos. A maior rejei\u00e7\u00e3o \u00e9 de Pantale\u00e3o, que tem 33%. Na sequ\u00eancia aparecem Z\u00e9 Gomes (30%), Jair Pedro (26%), Miguel Anacleto (24%), Armando Monteiro (20%) e Paulo C\u00e2mara (14%).<\/font><\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Pesquisa Datafolha divulgada nesta quarta-feira (10) aponta os seguintes percentuais de inten\u00e7\u00e3o de voto na corrida para o governo de Pernambuco: Paulo C\u00e2mara tem 39% e Armando Monteiro, 33%, aponta Datafolha. Margem de erro \u00e9 de tr\u00eas pontos percentuais, para mais ou para menos. Instituto entrevistou 1.211 eleitores entre 8 e 9 de setembro. Pesquisa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1281","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=1281"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1281\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=1281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=1281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=1281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}