{"id":1133,"date":"2014-07-21T21:00:00","date_gmt":"2014-07-21T21:00:00","guid":{"rendered":"https:\/\/saloanoticias.mrmediaweb.com\/v1\/2014\/07\/21\/dica-de-saude-da-byofarma-de-garanhuns\/"},"modified":"2014-07-21T21:00:00","modified_gmt":"2014-07-21T21:00:00","slug":"dica-de-saude-da-byofarma-de-garanhuns","status":"publish","type":"post","link":"https:\/\/www.saloanoticias.com\/v1\/dica-de-saude-da-byofarma-de-garanhuns\/","title":{"rendered":"MAIS UMA DICA DE SA\u00daDE DA BYOFARMA DE GARANHUNS PARA VOC\u00ca"},"content":{"rendered":"<p align=\"justify\"><font size=\"3\" face=\"Arial\"><a href=\"http:\/\/www.saloanoticias.com\/images\/10570468_657372197673628_327594933065714312_n.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"10570468_657372197673628_327594933065714312_n\" style=\"border-left-width: 0px; border-right-width: 0px; background-image: none; border-bottom-width: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 0px auto 10px; display: block; padding-right: 0px; border-top-width: 0px\" border=\"0\" alt=\"10570468_657372197673628_327594933065714312_n\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/10570468_657372197673628_327594933065714312_n_thumb.jpg\" width=\"529\" height=\"381\"><\/a>Quer estimular sua saciedade e emagrecer com sa\u00fade? A spirulina cont\u00e9m uma subst\u00e2ncia chamada fenilalanina, que estimula a saciedade, a spirulina \u00e9 comumente chamada de alga, quando na verdade ela \u00e9 uma cianobact\u00e9ria &#8211; bact\u00e9ria capaz de fazer fotoss\u00edntese, como as plantas. O nutr\u00f3logo Roberto Navarro, da Associa\u00e7\u00e3o Brasileira de Nutrologia, afirma que a spirulina \u00e9 indicada para quem faz dieta hipocal\u00f3rica, como uma forma de complementar o consumo de nutrientes.<\/font>  <\/p>\n<p align=\"justify\"><a href=\"http:\/\/www.saloanoticias.com\/images\/byofarma-logo_f4963e8622ea187634dcbf2d2183b152.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"ByoFarma Logo\" style=\"border-left-width: 0px; border-right-width: 0px; background-image: none; border-bottom-width: 0px; float: none; padding-top: 0px; padding-left: 0px; margin: 10px auto; display: block; padding-right: 0px; border-top-width: 0px\" border=\"0\" alt=\"ByoFarma Logo\" src=\"http:\/\/www.saloanoticias.com\/v1\/wp-content\/uploads\/imagens\/byofarma-logo_thumb_38dfa184f1f31030d54384b8974406f7.jpg\" width=\"525\" height=\"394\"><\/a>  <\/p>\n<p align=\"justify\"><font size=\"3\" face=\"Arial\">No geral, ela \u00e9 manipulada e receitada na forma de c\u00e1psula. Quando consumida antes das refei\u00e7\u00f5es, ela forma uma esp\u00e9cie de gel no est\u00f4mago, que desacelera o esvaziamento g\u00e1strico e diminui a fome. Este gel tamb\u00e9m protege a mucosa g\u00e1strica auxiliando na redu\u00e7\u00e3o de sintomas de gastrite e \u00falceras gastroduodenais.<\/font><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Quer estimular sua saciedade e emagrecer com sa\u00fade? A spirulina cont\u00e9m uma subst\u00e2ncia chamada fenilalanina, que estimula a saciedade, a spirulina \u00e9 comumente chamada de alga, quando na verdade ela \u00e9 uma cianobact\u00e9ria &#8211; bact\u00e9ria capaz de fazer fotoss\u00edntese, como as plantas. O nutr\u00f3logo Roberto Navarro, da Associa\u00e7\u00e3o Brasileira de Nutrologia, afirma que a spirulina [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1133","post","type-post","status-publish","format-standard","hentry","category-noticias-do-dia"],"_links":{"self":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":0,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/posts\/1133\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/media?parent=1133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/categories?post=1133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saloanoticias.com\/v1\/wp-json\/wp\/v2\/tags?post=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}